{"id":9000,"date":"2019-09-20T10:45:50","date_gmt":"2019-09-20T13:45:50","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/?p=9000"},"modified":"2019-09-26T14:36:14","modified_gmt":"2019-09-26T17:36:14","slug":"no-a-la-trata-de-personas","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/no-a-la-trata-de-personas\/","title":{"rendered":"No a la \u00abTrata de Personas\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-9001\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/09\/pALMIRA-1-1000x848.png\" alt=\"\" width=\"1000\" height=\"848\" srcset=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/09\/pALMIRA-1-1000x848.png 1000w, https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/09\/pALMIRA-1-768x651.png 768w, https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/09\/pALMIRA-1.png 1500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>El jueves 19 de setiembre se llev\u00f3 a cabo la charla sobre \u00abTrata de Personas\u00bb, tem\u00e1tica abordada desde el espacio Pr\u00e1cticas de Lectura, Escritura y Oralidad, a cargo de los Estudiantes de primer a\u00f1o de PEP, sede Palmira \u00a0y la direcci\u00f3n de la Prof.Gabriela Chac\u00f3n.<\/p>\n<p>Participaron la Rectora del IES 9-001, Prof. Laura Soto, la Coordinadora Natalia Ponce, estudiantes y referentes del Centro de Estudiantes.<\/p>\n<p>Se produjo un interesante y necesario intercambio de ideas fundamentales para la toma de conciencia de tan \u00a0compleja tem\u00e1tica, que invita a llevar a la acci\u00f3n, una actitud comprometida y necesaria para combatir este flagelo\u00a0 injustificable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 19 de setiembre se llev\u00f3 a cabo la charla sobre \u00abTrata de Personas\u00bb, tem\u00e1tica abordada desde el espacio Pr\u00e1cticas de Lectura, Escritura y Oralidad, a cargo de los Estudiantes de primer a\u00f1o de PEP, sede Palmira \u00a0y la direcci\u00f3n de la Prof.Gabriela Chac\u00f3n. Participaron la Rectora del IES 9-001, Prof. Laura Soto, la &#8230; <a title=\"No a la \u00abTrata de Personas\u00bb\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/no-a-la-trata-de-personas\/\" aria-label=\"More on No a la \u00abTrata de Personas\u00bb\">[+]<\/a><\/p>\n","protected":false},"author":6806,"featured_media":9162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[102],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/9000"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6806"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=9000"}],"version-history":[{"count":2,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/9000\/revisions"}],"predecessor-version":[{"id":9003,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/9000\/revisions\/9003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media\/9162"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=9000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=9000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=9000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}