{"id":8465,"date":"2019-06-22T21:36:49","date_gmt":"2019-06-23T00:36:49","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/?p=8465"},"modified":"2019-06-22T21:37:15","modified_gmt":"2019-06-23T00:37:15","slug":"disenando-caminos-desfile-solidario-ies-9-001","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/disenando-caminos-desfile-solidario-ies-9-001\/","title":{"rendered":"Dise\u00f1ando caminos, desfile solidario &#8211; IES 9-001"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/CS26URbHfRI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Dise\u00f1ando caminos, desfile solidario del IEDyT 9001 \u201cGral. Jos\u00e9 de San Mart\u00edn. Centro de Congresos y Exposiciones.<br \/>\nLos objetivos de este evento fueron, en primer lugar, dar a conocer las propuestas de formaci\u00f3n T\u00e9cnica Superior del IEDyT 9001 \u201cGral. Jos\u00e9 de San Mart\u00edn\u201d, principalmente la nueva \u201cTecnicatura Superior en Dise\u00f1o de Indumentaria, Textil y Accesorios\u201d, la cual en este 2019 tendr\u00e1 su primer promoci\u00f3n. En segundo lugar, tender lazos a la comunidad y entre los distintos sectores productivos, econ\u00f3micos y comerciales para mejorar y fortalecer el sector de indumentaria-textil. Y por \u00faltimo institucionalizar la propuesta para que cada a\u00f1o se repita y crezca, permitiendo la ayuda solidaria a distintos espacios de nuestra comunidad, como as\u00ed tambi\u00e9n generar un respaldo econ\u00f3mico para la generaci\u00f3n y sustentabilidad de las actividades de las Tecnicaturas.<\/p>\n<p>Adem\u00e1s, los asistentes disfrutaron de patios de comidas, exposiciones y sorteos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1ando caminos, desfile solidario del IEDyT 9001 \u201cGral. Jos\u00e9 de San Mart\u00edn. Centro de Congresos y Exposiciones. Los objetivos de este evento fueron, en primer lugar, dar a conocer las propuestas de formaci\u00f3n T\u00e9cnica Superior del IEDyT 9001 \u201cGral. Jos\u00e9 de San Mart\u00edn\u201d, principalmente la nueva \u201cTecnicatura Superior en Dise\u00f1o de Indumentaria, Textil y Accesorios\u201d, &#8230; <a title=\"Dise\u00f1ando caminos, desfile solidario &#8211; IES 9-001\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/disenando-caminos-desfile-solidario-ies-9-001\/\" aria-label=\"More on Dise\u00f1ando caminos, desfile solidario &#8211; IES 9-001\">[+]<\/a><\/p>\n","protected":false},"author":6806,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8465"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6806"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=8465"}],"version-history":[{"count":1,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8465\/revisions"}],"predecessor-version":[{"id":8466,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8465\/revisions\/8466"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=8465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=8465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=8465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}