{"id":8392,"date":"2019-06-13T11:47:03","date_gmt":"2019-06-13T14:47:03","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/?p=8392"},"modified":"2019-06-13T12:10:55","modified_gmt":"2019-06-13T15:10:55","slug":"13-de-junio-por-que-se-celebra-el-dia-del-escritor","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/13-de-junio-por-que-se-celebra-el-dia-del-escritor\/","title":{"rendered":"13 de Junio: \u00bfPor qu\u00e9 se celebra el D\u00eda del Escritor?"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-8394\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/06\/escritor.jpg\" alt=\"\" width=\"960\" height=\"783\" srcset=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/06\/escritor.jpg 960w, https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/06\/escritor-768x626.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p style=\"background: white; vertical-align: baseline; margin: 0cm 0cm 12.0pt 0cm;\"><span style=\"font-size: 13.5pt; font-family: 'Arial','sans-serif';\">La fecha celebra el nacimiento de Leopoldo Lugones, fundador de la Sociedad Argentina de Escritores.<\/span><\/p>\n<p style=\"background: white; vertical-align: baseline; font-variant-ligatures: normal; font-variant-caps: normal; font-variant-numeric: inherit; font-variant-east-asian: inherit; font-stretch: inherit; line-height: inherit; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px; margin: 0cm 0cm 12.0pt 0cm;\"><span style=\"font-size: 13.5pt; font-family: 'Arial','sans-serif';\">El 13 de junio de 1874 nac\u00eda el poeta, ensayista, periodista y pol\u00edtico, Leopoldo Lugones. Es en su memoria que se instituy\u00f3 el D\u00eda del Escritor. Fundador y primer presidente de la Sociedad Argentina de Escritores, Lugones es reconocido como un precursor y figura clave en la configuraci\u00f3n de la literatura argentina.<\/span><\/p>\n<p style=\"background: white; vertical-align: baseline; font-variant-ligatures: normal; font-variant-caps: normal; font-variant-numeric: inherit; font-variant-east-asian: inherit; font-stretch: inherit; line-height: inherit; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px; margin: 0cm 0cm 12.0pt 0cm;\"><span style=\"font-size: 13.5pt; font-family: 'Arial','sans-serif';\">Leopoldo Lugones public\u00f3 35 libros en vida, entre los que se destacan \u201cLos crep\u00fasculos del jard\u00edn\u201d, \u201cLunario sentimental\u201d, \u201cEl libro fiel\u201d, \u201cEl libro de los paisajes\u201d, \u201cLas fuerzas extra\u00f1as\u201d, \u201cLa guerra gaucha\u201d, \u201cLas horas doradas\u201d, entre otros.<\/span><\/p>\n<p style=\"background: white; vertical-align: baseline; font-variant-ligatures: normal; font-variant-caps: normal; font-variant-numeric: inherit; font-variant-east-asian: inherit; font-stretch: inherit; line-height: inherit; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px; margin: 0cm 0cm 12.0pt 0cm;\"><span style=\"font-size: 13.5pt; font-family: 'Arial','sans-serif';\">Hace poco tiempo, la Biblioteca Nacional recuper\u00f3 algunos de sus manuscritos, que fueron destinados al Museo del Libro y de la Lengua.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>Feliz d\u00eda a todos los escritores!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fecha celebra el nacimiento de Leopoldo Lugones, fundador de la Sociedad Argentina de Escritores. El 13 de junio de 1874 nac\u00eda el poeta, ensayista, periodista y pol\u00edtico, Leopoldo Lugones. Es en su memoria que se instituy\u00f3 el D\u00eda del Escritor. Fundador y primer presidente de la Sociedad Argentina de Escritores, Lugones es reconocido como &#8230; <a title=\"13 de Junio: \u00bfPor qu\u00e9 se celebra el D\u00eda del Escritor?\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/13-de-junio-por-que-se-celebra-el-dia-del-escritor\/\" aria-label=\"More on 13 de Junio: \u00bfPor qu\u00e9 se celebra el D\u00eda del Escritor?\">[+]<\/a><\/p>\n","protected":false},"author":6806,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8392"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6806"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=8392"}],"version-history":[{"count":2,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8392\/revisions"}],"predecessor-version":[{"id":8399,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8392\/revisions\/8399"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=8392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=8392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=8392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}