{"id":8063,"date":"2019-05-14T21:15:18","date_gmt":"2019-05-15T00:15:18","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/?p=8063"},"modified":"2019-05-14T21:15:18","modified_gmt":"2019-05-15T00:15:18","slug":"area-de-investigacion-convocatoria-abierta-el-9-001-investiga","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/area-de-investigacion-convocatoria-abierta-el-9-001-investiga\/","title":{"rendered":"\u00c1rea de Investigaci\u00f3n: Convocatoria abierta \u00abEl 9-001 Investiga\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-8050 alignleft\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2019\/05\/investigacion.jpeg\" alt=\"\" width=\"280\" height=\"180\" \/><\/p>\n<p>Desde el IESDyT 9001 \u201cGeneral Jos\u00e9 de San Mart\u00edn\u201d y la jefatura de investigaci\u00f3n, en el marco de la convocatoria de \u201c<strong>Nuevos proyectos de investigaci\u00f3n 2019<\/strong>\u201d de la CGES, invitamos a la conformaci\u00f3n de nuevos equipos de investigaci\u00f3n tanto de profesorados y tecnicaturas.<\/p>\n<p>Para ello deben presentar un pre proyecto siguiendo los siguientes formatos:<br \/>\n1.\u00a0<a title=\"https:\/\/drive.google.com\/open?id=1pRoF-7OJV85OOuAfR7cxIenn3ZedIV-0\" href=\"https:\/\/drive.google.com\/open?id=1pRoF-7OJV85OOuAfR7cxIenn3ZedIV-0\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/drive.google.com\/open?id%3D1pRoF-7OJV85OOuAfR7cxIenn3ZedIV-0&amp;source=gmail&amp;ust=1557965412610000&amp;usg=AFQjCNGYKcSIK3akBrc4QDjVLciZDp00NQ\">Proyectos de investigaci\u00f3n nuevos 2019 para carreras docentes<\/a>.<br \/>\n2.\u00a0<a title=\"https:\/\/drive.google.com\/open?id=1tNhubeGEKarQmTXLVea8Cy80tw5V7hwm \" href=\"https:\/\/drive.google.com\/open?id=1tNhubeGEKarQmTXLVea8Cy80tw5V7hwm\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/drive.google.com\/open?id%3D1tNhubeGEKarQmTXLVea8Cy80tw5V7hwm&amp;source=gmail&amp;ust=1557965412610000&amp;usg=AFQjCNHnUNrWd-fhA740psDu9698oE--4A\">Proyectos de investigaci\u00f3n nuevos 2019 para carreras t\u00e9cnicas<\/a>.<\/p>\n<p>Los pre informes pueden enviarse hasta el\u00a0<strong>31 de Mayo de 2019<\/strong>, al siguiente correo-e:\u00a0<a href=\"mailto:mariacarinamicheli@gmail.com\" target=\"_blank\" rel=\"noopener\">mariacarinamicheli@gmail.com<\/a>.<\/p>\n<p>Cualquier inquietud comunicarse con la profesora\u00a0<strong>Carina Micheli<\/strong>, los d\u00edas\u00a0<strong>lunes<\/strong><br \/>\n<strong>o jueves de 13 a 18.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el IESDyT 9001 \u201cGeneral Jos\u00e9 de San Mart\u00edn\u201d y la jefatura de investigaci\u00f3n, en el marco de la convocatoria de \u201cNuevos proyectos de investigaci\u00f3n 2019\u201d de la CGES, invitamos a la conformaci\u00f3n de nuevos equipos de investigaci\u00f3n tanto de profesorados y tecnicaturas. Para ello deben presentar un pre proyecto siguiendo los siguientes formatos: 1.\u00a0Proyectos &#8230; <a title=\"\u00c1rea de Investigaci\u00f3n: Convocatoria abierta \u00abEl 9-001 Investiga\u00bb\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/area-de-investigacion-convocatoria-abierta-el-9-001-investiga\/\" aria-label=\"More on \u00c1rea de Investigaci\u00f3n: Convocatoria abierta \u00abEl 9-001 Investiga\u00bb\">[+]<\/a><\/p>\n","protected":false},"author":6806,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8063"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6806"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=8063"}],"version-history":[{"count":1,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8063\/revisions"}],"predecessor-version":[{"id":8064,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/8063\/revisions\/8064"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=8063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=8063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=8063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}