{"id":7300,"date":"2018-12-20T12:47:50","date_gmt":"2018-12-20T15:47:50","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/?p=7300"},"modified":"2018-12-20T12:52:19","modified_gmt":"2018-12-20T15:52:19","slug":"inscripciones-para-cubrir-espacios-curriculares-y-cargos-administrativos-para-el-ciclo-2019","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/inscripciones-para-cubrir-espacios-curriculares-y-cargos-administrativos-para-el-ciclo-2019\/","title":{"rendered":"Inscripciones para cubrir Espacios Curriculares y Cargos Administrativos para el Ciclo 2019"},"content":{"rendered":"<p>El Equipo de Gesti\u00f3n del Instituto de Formaci\u00f3n Docente y T\u00e9cnico N\u00b09-001 General San Mart\u00edn, informa que la\u00a0<strong>Convocatoria a la Inscripci\u00f3n masiva de Docentes para cubrir espacios curriculares y Cargos Administrativos para el ciclo lectivo 2019<\/strong>, estar\u00e1 habilitado\u00a0<strong>desde el 20 de diciembre del 2018 al 20 de febrero de 2019 inclusive<\/strong>.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2018\/12\/Formulario.png\" width=\"127\" height=\"127\" border=\"0\" data-imagetype=\"External\" \/>A los aspirantes de la instituci\u00f3n, como as\u00ed tambi\u00e9n quienes que no pertenecen a la misma, se les recomienda completar todos los campos del formulario a fin de que el mismo se registre de forma completa en nuestra base de datos y seguir los siguientes pasos:<\/p>\n<p>1) Completar el formulario de inscripci\u00f3n como postulantes para cubrir cargos en esta instituci\u00f3n. Al acceder al formulario en l\u00ednea deber\u00e1 consignar sus datos personales, y quienes sean aspirantes a cargos docentes ingresar al respectivo formulario (ya sea de profesorados o tecnicaturas), y seleccionar los espacios a los que desea inscribirse:<\/p>\n<ul>\n<li><a href=\"https:\/\/goo.gl\/forms\/DH2MnaZoTccd56bw2\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">Acceder al formulario de inscripci\u00f3n a espacios curriculares de\u00a0<strong>PROFESORADOS<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/goo.gl\/forms\/A4vbK4iAjWA9wikg2\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">Acceder al formulario de inscripci\u00f3n a espacios curriculares de\u00a0<strong>TECNICATURAS<\/strong><\/a>.<\/li>\n<li><a href=\"https:\/\/goo.gl\/forms\/MnWPJelLr6ArpEs82\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">Acceder al formulario de inscripci\u00f3n para cargos\u00a0<strong>ADMINISTRATIVOS<\/strong><\/a>.<\/li>\n<\/ul>\n<p>2) Adjuntar al correo\u00a0<a href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/aula\/mailto:inscripciones9001@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">inscripciones9001@gmail.com<\/a>\u00a0su CV en un archivo tipo: Doc. O PDF con una extensi\u00f3n m\u00e1xima de 4(cuatro) p\u00e1ginas A4 conteniendo los siguientes \u00edtems:<\/p>\n<ul>\n<li>Datos personales (apellidos, nombre, DNI, tel\u00e9fono, fecha de nacimiento, email).<\/li>\n<li>Datos de titulaci\u00f3n (T\u00edtulo Nivel Superior de 4 a\u00f1os o m\u00e1s, T\u00edtulo de posgrado).<\/li>\n<li>Trabajos publicados con N\u00b0 de registro de propiedad intelectual (ISBN) y pertenecientes al espacio en el que se inscribe.<\/li>\n<li>Conferencias\/Ponencias dictadas espec\u00edficas al espacio en el que se inscribe (en los \u00faltimos 10 a\u00f1os).<\/li>\n<li>Cursos realizados aprobados mediante evaluaci\u00f3n, mayor a 12 horas c\u00e1tedras (en los \u00faltimos \u00a010 a\u00f1os).<\/li>\n<li>Cursos dictados con N\u00b0 de Resoluci\u00f3n pertinentes al espacio en el que se inscribe (en los \u00faltimos 10 a\u00f1os).<\/li>\n<li>Posgrados aprobados.<\/li>\n<li>Investigaciones realizadas de \u00e1mbito pedag\u00f3gico y\/o espec\u00edfico en el que se inscribe (en los \u00faltimos 10 a\u00f1os).<\/li>\n<\/ul>\n<p><strong>En el momento en que se lo requiera, el docente \u00a0deber\u00e1 presentar personalmente las probanzas de lo expresado en su curriculum.<\/strong><\/p>\n<p>La convocatoria durante el ciclo lectivo 2019 para cubrir cargos de horas c\u00e1tedras mediante correo-mail y en publicaciones en los diarios UNO y Los Andes.<\/p>\n<p>Saludos cordiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Equipo de Gesti\u00f3n del Instituto de Formaci\u00f3n Docente y T\u00e9cnico N\u00b09-001 General San Mart\u00edn, informa que la\u00a0Convocatoria a la Inscripci\u00f3n masiva de Docentes para cubrir espacios curriculares y Cargos Administrativos para el ciclo lectivo 2019, estar\u00e1 habilitado\u00a0desde el 20 de diciembre del 2018 al 20 de febrero de 2019 inclusive. A los aspirantes de &#8230; <a title=\"Inscripciones para cubrir Espacios Curriculares y Cargos Administrativos para el Ciclo 2019\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/inscripciones-para-cubrir-espacios-curriculares-y-cargos-administrativos-para-el-ciclo-2019\/\" aria-label=\"More on Inscripciones para cubrir Espacios Curriculares y Cargos Administrativos para el Ciclo 2019\">[+]<\/a><\/p>\n","protected":false},"author":6806,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/7300"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6806"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=7300"}],"version-history":[{"count":2,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/7300\/revisions"}],"predecessor-version":[{"id":7302,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/7300\/revisions\/7302"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=7300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=7300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=7300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}