{"id":3643,"date":"2012-11-28T02:20:00","date_gmt":"2012-11-27T23:20:00","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/acto-de-colacion-de-grado-fotos-2\/"},"modified":"2012-11-28T02:20:00","modified_gmt":"2012-11-27T23:20:00","slug":"acto-de-colacion-de-grado-fotos-2","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/acto-de-colacion-de-grado-fotos-2\/","title":{"rendered":"Acto de colaci\u00f3n de grado &#8211; Fotos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"background-color: #3192a5; width: 500px;\" border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/plus.google.com\/photos\/104638810255718924056\/albums\/5813986675495182449#photos\/104638810255718924056\/albums\/5813986675495182449\/5813986925361354370\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2018\/08\/actocolac_1.jpg\" border=\"0\" alt=\"\" width=\"469\" height=\"338\"><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/plus.google.com\/photos\/104638810255718924056\/albums\/5813986675495182449#photos\/104638810255718924056\/albums\/5813986675495182449\/5813986925361354370\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2018\/08\/manitoclic.gif\" border=\"0\" alt=\"\"><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\"><strong><span style=\"color: #ffffff;\">Clic para ver fotos<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: left;\">&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">El Instituto de Educaci&oacute;n Superior Docente y T&eacute;cnica N&ordm; 9-001 &ldquo;General Jos&eacute; de San Mart&iacute;n&rdquo; realiz&oacute; el Acto de Colaci&oacute;n de Grado para las Promociones 2011- 2012 y Despedida de Jubilados, el d&iacute;a 22 de Noviembre a las 19:30 horas en el Auditorio de la Instituci&oacute;n.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En la oportunidad, despu&eacute;s de las palabras de bienvenida e ingreso al auditorio de los egresados, se form&oacute; la mesa acad&eacute;mica con las siguientes autoridades:<\/span><\/p>\n<p><span style=\"color: #ffffff;\">&#8211; Directora de Educaci&oacute;n Superior: Mgter Alicia Romero;<\/span><br \/><span style=\"color: #ffffff;\">&#8211; Rector: Prof. Carlos A. G&oacute;mez;<\/span><br \/><span style=\"color: #ffffff;\">&#8211; Directora: Prof. Laura B. Soto; Concejal Sergio Tusedu;<\/span><br \/><span style=\"color: #ffffff;\">&#8211; Rector de IES N&ordm; 9-028 de Santa Rosa: Prof. Alejandro Fader;<\/span><br \/><span style=\"color: #ffffff;\">&#8211; Rector del IEF N&ordm; 9-016: Prof. Ra&uacute;l Brioude;<\/span><br \/><span style=\"color: #ffffff;\">&#8211; Directora del Nivel Medio de la Instituci&oacute;n: Prof. M. Teresa Arrar&aacute;s;<\/span><br \/><span style=\"color: #ffffff;\">&#8211; Ex Delegada de la Regional Este de la D.G.E.: Prof. Mercedes Mellado.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">&nbsp;<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En la oportunidad se realiz&oacute; el cambio de abanderados y escoltas, juramento de egresados, entrega de diplomas y reconocimiento a docentes jubilados.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Ver n&oacute;mina de egresados haciendo clic en comentarios<strong><span style=\"font-size: 12pt;\">&darr;&nbsp; <\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Clic para ver fotos &nbsp; El Instituto de Educaci&oacute;n Superior Docente y T&eacute;cnica N&ordm; 9-001 &ldquo;General Jos&eacute; de San Mart&iacute;n&rdquo; realiz&oacute; el Acto de Colaci&oacute;n de Grado para las Promociones 2011- 2012 y Despedida de Jubilados, el d&iacute;a 22 de Noviembre a las 19:30 horas en el Auditorio de la Instituci&oacute;n. En la &#8230; <a title=\"Acto de colaci\u00f3n de grado &#8211; Fotos\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/acto-de-colacion-de-grado-fotos-2\/\" aria-label=\"More on Acto de colaci\u00f3n de grado &#8211; Fotos\">[+]<\/a><\/p>\n","protected":false},"author":6607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3643"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6607"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3643"}],"version-history":[{"count":0,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3643\/revisions"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}