{"id":3603,"date":"2012-10-29T15:51:06","date_gmt":"2012-10-29T12:51:06","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/cine-cientifico\/"},"modified":"2012-10-29T15:51:06","modified_gmt":"2012-10-29T12:51:06","slug":"cine-cientifico","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/cine-cientifico\/","title":{"rendered":"Cine cient\u00edfico"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"background-color: #302668; width: 500px;\" border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2018\/08\/cinecie.jpg\" border=\"0\" alt=\"\" width=\"478\" height=\"364\"><\/p>\n<p style=\"padding-left: 30px;\"><strong><span style=\"color: #ffffff; font-size: 10pt;\">NANOTECNOLOG&Iacute;A, LA FRONTERA DE LOS &Aacute;TOMOS<\/span><\/strong><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">(2006)<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">&nbsp;<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">La nanotecnolog&iacute;a es un campo verdaderamente emocionante, y ahora que estamos inmersos en este terrible problema energ&eacute;tico con consecuencias pol&iacute;ticas graves, tal vez pueda brindarnos una soluci&oacute;n al problema. La nanotecnolog&iacute;a ha erigido a la bacteria como s&iacute;mbolo del futuro. Y es que a escalas tan bajas, la naturaleza nos lleva mucha ventaja en el dise&ntilde;o de soluciones.<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Ahora resulta que las m&aacute;quinas y los robots del futuro no ser&aacute;n en absoluto como los hemos imaginado. En lugar de estructuras brillantes y sobredimensionadas ser&aacute;n enanas y blandas como una bacteria. &iquest;Qu&eacute; es una bacteria sino un nanorobot autoreplicante? Y el futuro ser&aacute; de los nanorobots de una mil&eacute;sima parte de un mil&iacute;metro en el caso de la bacteria..<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Junto a Richard Jones, F&iacute;sico de la universidad de Sheffield, Inglaterra, recorremos la ciencia y la tecnolog&iacute;a de la escala nanom&eacute;trica. Y parece que la visi&oacute;n que nos dio la pel&iacute;cula &ldquo;Viaje Alucinante&rdquo;, con Rachel Welch, no era del todo acertada.<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Jordi Pascual, Director del Institut Catal&agrave; de Nanotecnolog&iacute;a, y Nicol&aacute;s Garc&iacute;a, Director del laboratorio de F&iacute;sica de Sistemas peque&ntilde;os y Nanotecnolog&iacute;a, nos acompa&ntilde;an para ver las posibilidades de esta ciencia tan prometedora.<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">&nbsp;<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Producci&oacute;n: TVE (Televiis&oacute;n Espa&ntilde;ola) S.A. y Agencia Planetaria<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Realizaci&oacute;n: Juan Gamero, Gonzalo Bello y Xavier Vela<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Direcci&oacute;n: Eduard Punset<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Duraci&oacute;n: 52 minutos<\/span><\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #ffffff; font-size: 10pt;\">Origen: Espa&ntilde;a<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; NANOTECNOLOG&Iacute;A, LA FRONTERA DE LOS &Aacute;TOMOS (2006) &nbsp; La nanotecnolog&iacute;a es un campo verdaderamente emocionante, y ahora que estamos inmersos en este terrible problema energ&eacute;tico con consecuencias pol&iacute;ticas graves, tal vez pueda brindarnos una soluci&oacute;n al problema. La nanotecnolog&iacute;a ha erigido a la bacteria como s&iacute;mbolo del futuro. Y es que a escalas &#8230; <a title=\"Cine cient\u00edfico\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/cine-cientifico\/\" aria-label=\"More on Cine cient\u00edfico\">[+]<\/a><\/p>\n","protected":false},"author":6607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3603"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6607"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3603"}],"version-history":[{"count":0,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3603\/revisions"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}