{"id":3179,"date":"2011-10-01T16:41:00","date_gmt":"2011-10-01T13:41:00","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/curso-sobre-atahualpa-yupanqui-2\/"},"modified":"2011-10-01T16:41:00","modified_gmt":"2011-10-01T13:41:00","slug":"curso-sobre-atahualpa-yupanqui-2","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/curso-sobre-atahualpa-yupanqui-2\/","title":{"rendered":"Curso sobre Atahualpa Yupanqui"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" src=\"\" border=\"0\" width=\"526\" height=\"390\"><\/p>\n<table style=\"background-color: #6cf87a; width: 531px; height: 22px; margin-left: auto; margin-right: auto;\" border=\"0\">\n<tbody>\n<tr>\n<td>\n<p>&nbsp;<\/p>\n<p class=\"Estilo\"><span style=\"font-size: 10pt;\">&nbsp;&nbsp; Eliana Abdala nos emocion&oacute; con su curso sobre <strong>Atahualpa Yupanqui<\/strong> (H&eacute;ctor Roberto Chavero). Hu&eacute;rfano de padre muy joven, debi&oacute; trabajar en muy diversos oficios desde arriero a maestro de escuela. Hered&oacute; de su padre el amor a la lectura, quiz&aacute;s, sea para muchos desconocida su formaci&oacute;n intelectual y humana, concurr&iacute;a todas las noches a la Biblioteca Nacional, all&iacute; ley&oacute; obras de &nbsp;escritores locales y universales.<\/span><\/p>\n<p class=\"Estilo\"><span style=\"font-size: 10pt;\">Fue un excelente guitarrista y su poes&iacute;a merece un lugar destacado en la historia de la literatura argentina. Eliana Abdala estudi&oacute; el&nbsp; corpus po&eacute;tico de Atahualpa Yupanqui sobre la base de los marcos te&oacute;ricos de la literatura.&nbsp; Es el primer estudio realizado de sus poemas&nbsp; desde la hermen&eacute;utica, analiz&oacute;&nbsp; el aspecto local&nbsp; y universal de sus versos, descubriendo &nbsp;los s&iacute;mbolos yupanquianos en palabras sencillas.<\/span><\/p>\n<p class=\"Estilo\"><span style=\"font-size: 10pt;\">Atahualpa vivi&oacute; en Par&iacute;s,&nbsp; actu&oacute; en Jap&oacute;n y, tambi&eacute;n, recorri&oacute; &nbsp;Salta, Jujuy y Bolivia a caballo, durmiendo en cualquier parte y conviviendo con los nativos. Consideraba que solo a caballo puede conocerse profundamente la geograf&iacute;a y &nbsp;el lamento de sus habitantes.<\/span><\/p>\n<p class=\"Estilo\"><span style=\"font-size: 10pt;\"><strong>Eliana Abdala<\/strong> en su libro, <strong><em>&ldquo;La poes&iacute;a de Atahualpa Yupanqui&rdquo;,&nbsp; <\/em><\/strong>expresa que&nbsp; Don Atahualpa frecuentaba&nbsp; ambientes literarios pero se sent&iacute;a ajeno a la generaci&oacute;n de poetas seguidores del vanguardismo o \u00abde la psicolog&iacute;a de la gente rica\u00bb, como &eacute;l mismo dijera. Al respecto y preocupado por darle forma a un estilo que lo va caracterizando como poeta, como hombre de hondas ra&iacute;ces&nbsp; folkl&oacute;ricas, &eacute;l mismo declara:<\/span><\/p>\n<p class=\"Estilo\"><strong><span style=\"font-size: 10pt;\"><em>&ldquo;Nuestros poetas le adjudican al pueblo sus personales angustias, que no siempre coinciden con las del pueblo. De ah&iacute; la proliferaci&oacute;n de la poes&iacute;a amatoria <\/em><em>y <\/em><em>el silencio en torno a la justicia social ( &#8230; ). Cuando fui a buscar al paisano norte&ntilde;o, encontr&eacute; un paisaje de pobreza y paup&eacute;rrimo ( &#8230; ). As&iacute; salieron canciones con sentido de pena ( &#8230; ) &ldquo;<\/em><\/span><\/strong><\/p>\n<p class=\"Estilo\"><span style=\"font-size: 10pt;\">El curso se desarroll&oacute; en un c&aacute;lido ambiente, pues el padre de una de las alumnas del IES 9-001, asistente al curso, hab&iacute;a conocido a Don Atahualpa y expres&oacute; algunas an&eacute;cdotas vividas en Cerro Colorado.<\/span><\/p>\n<p class=\"Estilo\"><span style=\"font-size: 10pt;\">El d&iacute;a s&aacute;bado 24 de septiembre, Eliana Abdala nos sorprendi&oacute;&nbsp; con la presencia de Jos&eacute; Se&ntilde;a, cantante que pertenece &nbsp;al Programa Nacional &ldquo;Yo tengo muchos hermanos&rdquo;. Luego de embelesarnos con su voz, se dio por finalizado el curso&nbsp; hasta el d&iacute;a 20 de octubre, fecha en que se entregar&aacute;n los trabajos de an&aacute;lisis &nbsp;de poemas para ser evaluados.<\/span><\/p>\n<p style=\"text-align: right;\">A.O.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp;&nbsp; Eliana Abdala nos emocion&oacute; con su curso sobre Atahualpa Yupanqui (H&eacute;ctor Roberto Chavero). Hu&eacute;rfano de padre muy joven, debi&oacute; trabajar en muy diversos oficios desde arriero a maestro de escuela. Hered&oacute; de su padre el amor a la lectura, quiz&aacute;s, sea para muchos desconocida su formaci&oacute;n intelectual y humana, concurr&iacute;a todas las &#8230; <a title=\"Curso sobre Atahualpa Yupanqui\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/curso-sobre-atahualpa-yupanqui-2\/\" aria-label=\"More on Curso sobre Atahualpa Yupanqui\">[+]<\/a><\/p>\n","protected":false},"author":6607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3179"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6607"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3179"}],"version-history":[{"count":0,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3179\/revisions"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}