{"id":3156,"date":"2011-09-21T17:28:42","date_gmt":"2011-09-21T14:28:42","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/contundentes-palabras\/"},"modified":"2011-09-21T17:28:42","modified_gmt":"2011-09-21T14:28:42","slug":"contundentes-palabras","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/contundentes-palabras\/","title":{"rendered":"Contundentes palabras&#8230;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"background-color: #087265; width: 543px; height: 22px;\" border=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">Contundentes palabras de la presidenta Cristina Fernandez de kirchner<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">hoy en la ONU. Reclam&oacute; la necesidad de revisar los organismos que<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">califican la econom&iacute;a de los pa&iacute;ses y proclam&oacute; la arbitrariedad que<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">significa el poder de veto que tienen los poderosos del consejo de<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">seguridad. Propici&oacute; la entrada de Palestina como miembro y volvi&oacute;<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">sobre el tema Malvinas.<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">En un r&aacute;pido, pero certero, repaso hist&oacute;rico record&oacute; la Dictadura<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">genocida, los atentados terroristas del 92 y 94, el colonialismo<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">brit&aacute;nico que cumplir&aacute; en 2013 ochenta a&ntilde;os de usurpaci&oacute;n y la crisis<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">de 2001. Todo esto nos pas&oacute; a los argentinos, dijo, y es verdad.<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">La consideraci&oacute;n de estos temas, sostuvo, no debe tener color<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">pol&iacute;tico, es para todos los argentinos y de nosotros para el mundo.<\/span><br \/><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">Completa y absolutamente de acuerdo con usted se&ntilde;ora presidenta.<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: book antiqua,palatino; color: #ffffff; font-size: 12pt;\">Gustavo Bassin<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Contundentes palabras de la presidenta Cristina Fernandez de kirchnerhoy en la ONU. Reclam&oacute; la necesidad de revisar los organismos quecalifican la econom&iacute;a de los pa&iacute;ses y proclam&oacute; la arbitrariedad quesignifica el poder de veto que tienen los poderosos del consejo deseguridad. Propici&oacute; la entrada de Palestina como miembro y volvi&oacute;sobre el tema Malvinas.En &#8230; <a title=\"Contundentes palabras&#8230;\" class=\"read-more\" href=\"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/contundentes-palabras\/\" aria-label=\"More on Contundentes palabras&#8230;\">[+]<\/a><\/p>\n","protected":false},"author":6607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3156"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6607"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3156"}],"version-history":[{"count":0,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3156\/revisions"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}