{"id":3004,"date":"2011-05-17T00:47:00","date_gmt":"2011-05-16T21:47:00","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/escala-de-calificaciones-debate\/"},"modified":"2011-05-17T00:47:00","modified_gmt":"2011-05-16T21:47:00","slug":"escala-de-calificaciones-debate","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/escala-de-calificaciones-debate\/","title":{"rendered":"Escala de calificaciones- Debate"},"content":{"rendered":"<p><a href=\"index.cgi?wIdPub=20\">&nbsp;<span style=\"color: #ff0000;\">Link en comentarios<\/span><\/a><\/p>\n<p><span style=\"color: #ff0000;\"><a href=\"index.cgi?wIdPub=20\"><img decoding=\"async\" loading=\"lazy\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"\" border=\"0\" width=\"451\" height=\"287\"><\/a><\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Link en comentarios<\/p>\n","protected":false},"author":6607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3004"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6607"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3004"}],"version-history":[{"count":0,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3004\/revisions"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}