{"id":2992,"date":"2011-04-12T10:13:00","date_gmt":"2011-04-12T07:13:00","guid":{"rendered":"https:\/\/ens9001-mza.infd.edu.ar\/sitio\/expo-educativa-superior-2011\/"},"modified":"2011-04-12T10:13:00","modified_gmt":"2011-04-12T07:13:00","slug":"expo-educativa-superior-2011","status":"publish","type":"post","link":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/expo-educativa-superior-2011\/","title":{"rendered":"Expo educativa superior 2011"},"content":{"rendered":"<p><span style=\"color: #ff0000;\">&nbsp;link<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/des.mza.infd.edu.ar\/sitio\/index.cgi?wAccion=news&amp;wid_grupo_news=6&amp;wid_news=511\" target=\"_self\"><img decoding=\"async\" loading=\"lazy\" src=\"\" border=\"0\" width=\"416\" height=\"787\"><\/a>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;link &nbsp;<\/p>\n","protected":false},"author":6607,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/2992"}],"collection":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6607"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=2992"}],"version-history":[{"count":0,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/2992\/revisions"}],"wp:attachment":[{"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=2992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=2992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9001-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=2992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}